{"id":276,"date":"2012-03-31T12:18:27","date_gmt":"2012-03-31T12:18:27","guid":{"rendered":"http:\/\/www.ulusiada.pt\/clima\/?page_id=276"},"modified":"2012-05-02T17:24:45","modified_gmt":"2012-05-02T17:24:45","slug":"lei-das-vitualhas","status":"publish","type":"page","link":"https:\/\/www.ulusiada.pt\/clima\/ius-proprium-leis-gerais\/d-afonso-ii\/lei-das-vitualhas\/","title":{"rendered":"Lei das vitualhas"},"content":{"rendered":"<p>Lei, contra o antigo mau costume de Coimbra, vilas da Estremadura e do reino, impedindo os oven\u00e7ais do rei e os seus alcaides ou senhorios que dele tinham terras de levarem a ter\u00e7a das vitualhas daqueles que as vendiam para comer, sob pena de corregimento das coisas tomadas e pagamento de quinhentos soldos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lei, contra o antigo mau costume de Coimbra, vilas da Estremadura e do reino, impedindo os oven\u00e7ais do rei e os seus alcaides ou senhorios que dele tinham terras de levarem a ter\u00e7a das vitualhas daqueles que as vendiam para &hellip; <a href=\"https:\/\/www.ulusiada.pt\/clima\/ius-proprium-leis-gerais\/d-afonso-ii\/lei-das-vitualhas\/\">Continuar a ler <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":78,"menu_order":3,"comment_status":"closed","ping_status":"open","template":"lei-page.php","meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.ulusiada.pt\/clima\/wp-json\/wp\/v2\/pages\/276"}],"collection":[{"href":"https:\/\/www.ulusiada.pt\/clima\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ulusiada.pt\/clima\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ulusiada.pt\/clima\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ulusiada.pt\/clima\/wp-json\/wp\/v2\/comments?post=276"}],"version-history":[{"count":2,"href":"https:\/\/www.ulusiada.pt\/clima\/wp-json\/wp\/v2\/pages\/276\/revisions"}],"predecessor-version":[{"id":1053,"href":"https:\/\/www.ulusiada.pt\/clima\/wp-json\/wp\/v2\/pages\/276\/revisions\/1053"}],"up":[{"embeddable":true,"href":"https:\/\/www.ulusiada.pt\/clima\/wp-json\/wp\/v2\/pages\/78"}],"wp:attachment":[{"href":"https:\/\/www.ulusiada.pt\/clima\/wp-json\/wp\/v2\/media?parent=276"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}